{"id":2575,"date":"2018-07-22T13:03:22","date_gmt":"2018-07-22T11:03:22","guid":{"rendered":"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13.jpg"},"modified":"2018-07-22T13:03:32","modified_gmt":"2018-07-22T11:03:32","slug":"k07-kirsche-26-4-13","status":"inherit","type":"attachment","link":"https:\/\/www.bio-nickl.de\/wordpress\/fotos-von-der-bluete-zur-frucht\/k07-kirsche-26-4-13\/","title":{"rendered":"Kirschbl\u00fcte Ende April"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-2575","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"231\" src=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-300x231.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-300x231.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-768x590.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-1024x787.jpg 1024w\" sizes=\"auto, 100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Kirschbl\u00fcte Ende April<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2443,"height":1878,"file":"2018\/07\/K07-Kirsche-26.4.13.jpg","sizes":{"thumbnail":{"file":"K07-Kirsche-26.4.13-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-150x150.jpg"},"medium":{"file":"K07-Kirsche-26.4.13-300x231.jpg","width":300,"height":231,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-300x231.jpg"},"medium_large":{"file":"K07-Kirsche-26.4.13-768x590.jpg","width":768,"height":590,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-768x590.jpg"},"large":{"file":"K07-Kirsche-26.4.13-1024x787.jpg","width":1024,"height":787,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-1024x787.jpg"},"twentyseventeen-featured-image":{"file":"K07-Kirsche-26.4.13-2000x1200.jpg","width":2000,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-2000x1200.jpg"},"twentyseventeen-thumbnail-avatar":{"file":"K07-Kirsche-26.4.13-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13-100x100.jpg"},"full":{"file":"K07-Kirsche-26.4.13.jpg","width":2443,"height":1878,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"Canon PowerShot SX40 HS","caption":"","created_timestamp":"1367001526","copyright":"","focal_length":"4.3","iso":"100","shutter_speed":"0.008","title":"","orientation":"0","keywords":[]}},"post":2511,"source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/07\/K07-Kirsche-26.4.13.jpg","_links":{"self":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/media\/2575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2575"}]}}