{"id":2760,"date":"2018-08-23T13:38:20","date_gmt":"2018-08-23T11:38:20","guid":{"rendered":"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben.jpg"},"modified":"2018-08-23T13:38:33","modified_gmt":"2018-08-23T11:38:33","slug":"krokus-in-verschiedenen-farben","status":"inherit","type":"attachment","link":"https:\/\/www.bio-nickl.de\/wordpress\/fotos-fruehblueher\/krokus-in-verschiedenen-farben\/","title":{"rendered":"Krokusse in verschiedenen Farben"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-2760","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"187\" src=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-300x187.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-300x187.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-768x478.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-1024x637.jpg 1024w\" sizes=\"auto, 100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Krokusse in verschiedenen Farben<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4000,"height":2488,"file":"2018\/08\/Krokus-in-verschiedenen-Farben.jpg","sizes":{"thumbnail":{"file":"Krokus-in-verschiedenen-Farben-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-150x150.jpg"},"medium":{"file":"Krokus-in-verschiedenen-Farben-300x187.jpg","width":300,"height":187,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-300x187.jpg"},"medium_large":{"file":"Krokus-in-verschiedenen-Farben-768x478.jpg","width":768,"height":478,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-768x478.jpg"},"large":{"file":"Krokus-in-verschiedenen-Farben-1024x637.jpg","width":1024,"height":637,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-1024x637.jpg"},"twentyseventeen-featured-image":{"file":"Krokus-in-verschiedenen-Farben-2000x1200.jpg","width":2000,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-2000x1200.jpg"},"twentyseventeen-thumbnail-avatar":{"file":"Krokus-in-verschiedenen-Farben-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben-100x100.jpg"},"full":{"file":"Krokus-in-verschiedenen-Farben.jpg","width":4000,"height":2488,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben.jpg"}},"image_meta":{"aperture":"4.5","credit":"","camera":"Canon PowerShot SX40 HS","caption":"","created_timestamp":"1458223338","copyright":"","focal_length":"34.935","iso":"200","shutter_speed":"0.0015625","title":"","orientation":"1","keywords":[]}},"post":2746,"source_url":"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/08\/Krokus-in-verschiedenen-Farben.jpg","_links":{"self":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/media\/2760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2760"}]}}