{"id":172,"date":"2017-07-28T16:55:29","date_gmt":"2017-07-28T14:55:29","guid":{"rendered":"http:\/\/www.bio-nickl.de\/wordpress\/?page_id=172"},"modified":"2019-11-20T16:40:10","modified_gmt":"2019-11-20T15:40:10","slug":"5-klasse-skript-2-kompetenz-training","status":"publish","type":"page","link":"https:\/\/www.bio-nickl.de\/wordpress\/did-meth-paed\/5-klasse-skript-2-kompetenz-training\/","title":{"rendered":"5. Klasse Skript 2: Kompetenz-Training"},"content":{"rendered":"<p><span style=\"color: #800000;\"><em>In diesem Skript werden Hinweise zu den prozessbezogenen Kompetenzen gegeben, die schon immer Bestandteil eines guten Biologie-Unterrichts waren, jetzt aber genauer benannt und systematisiert werden und mit st\u00e4rkerer Gewichtung in den Unterricht eingebunden werden sollen. Dieses Skript wendet sich an Berufsanf\u00e4nger wie an erfahrene Lehrkr\u00e4fte, denn die Kompetenz-Orientierung ist in dieser Form und in diesem Umfang f\u00fcr alle neu.<br \/>\n<\/em><\/span><\/p>\n<p><span style=\"color: #800000;\"><em>W\u00f6rtliche Zitate aus dem LehrplanPLUS erscheinen in diesem Skript kursiv und in Anf\u00fchrungszeichen.<\/em><\/span><\/p>\n<p><em><span style=\"color: #993366;\">Vgl. auch das Skript &#8222;Kompetenztraining in der Unterstufe&#8220;<\/span><\/em><\/p>\n<p><span style=\"color: #800000;\"><em>Anleitungen einschlie\u00dflich methodisch-didaktischer Hinweise f\u00fcr eine Vielzahl von Versuchen und Untersuchungen sowie einige Modelle und Rollenspiele enth\u00e4lt der Akademiebericht Nr. 506 \u201e<strong>Bio? \u2013 logisch!<\/strong>\u201c der Akademie f\u00fcr Lehrerfortbildung und Personalf\u00fchrung (ALP), 2017 [<a href=\"https:\/\/alp.dillingen.de\/publikationen\/suche\/publikation.html?Nr=506\">Link<\/a>].<\/em><\/span><\/p>\n<p>Themen-\u00dcbersicht:<\/p>\n<ul>\n<li><a href=\"#b5skript2a1\"><span style=\"color: #0000ff;\">Allgemeine Vorgaben im LehrplanPLUS<\/span><\/a><\/li>\n<li><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"#b5skript2a2\">1\u00a0 Erkenntnisse gewinnen<\/a><\/span>\n<ul>\n<li><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"#b5skript2x11\">1.1 Experimente und Untersuchungen<\/a><\/span><\/li>\n<li><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"#b5skript2x12\">1.2 Modelle<\/a><\/span><\/li>\n<\/ul>\n<\/li>\n<li><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"#b5skript2a3\">2\u00a0 Kommunizieren<\/a><\/span><\/li>\n<li><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"#b5skript2a4\">3\u00a0 Bewerten<\/a><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"color: #ff6600;\">Zusammenfassung der prozessbezogenen Kompetenzen in der 5. Klasse: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/12\/Prozessbezogene-Kompetenzen-5.-Klasse.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/12\/Prozessbezogene-Kompetenzen-5.-Klasse.pdf\">pdf<\/a>]<\/span><\/li>\n<li><span style=\"color: #ff6600;\">Multimedia zu meinem Vortrag &#8222;Kompetenzen in der Unterstufe&#8220; [<a style=\"color: #ff6600;\" href=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2019\/11\/vbio-21.11.19-B-Kompetenztraining-Unterstufe.pptx\">pptx<\/a>]<\/span><\/li>\n<li><span style=\"color: #ff6600;\">Multimedia zu meinem Vortrag &#8222;Spracharbeit Unterstufe&#8220; [<a style=\"color: #ff6600;\" href=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2019\/11\/vbio-21.11.19-E-Spracharbeit.pptx\">pptx<\/a>]<\/span><\/li>\n<li><span style=\"color: #ff6600;\">Multimedia zu meinem Vortrag &#8222;Stoffverteilung Unterstufe&#8220; (Didaktik, Methodik [<a style=\"color: #ff6600;\" href=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2019\/11\/vbio-21.11.19-D-Didaktik-Methodik.pptx\">pptx<\/a>]<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h1><span style=\"color: #0000ff;\"><strong>Prozessbezogene<\/strong> <strong>Kompetenzen nach LehrplanPLUS<\/strong><\/span><\/h1>\n<p><span style=\"color: #0000ff;\"><strong><span id=\"b5skript2a1\" class=\"sta-anchor \" aria-hidden=\"true\"><\/span>Allgemeine Vorgaben im LehrplanPLUS<\/strong><\/span><\/p>\n<p>Der LehrplanPLUS unterscheidet zwischen Fachkompetenz (Fachwissen) und den prozess\u00adbezogenen Kompetenzen Erkenntnisse gewinnen, kommunizieren und bewerten, die f\u00fcr den Schwerpunkt Biologie in allgemeiner Form im Lernbereich 2.1 aufgelistet sind. Ein zuk\u00fcnfti\u00adger bun\u00addes\u00adweiter Aufgabenpool wird sich auch auf die pro\u00adzessbezogenen Kompetenzen beziehen. Der <strong>Serviceteil<\/strong> des LehrplanPLUS bietet Erl\u00e4uterun\u00adgen, Querverweise, Materialien (f\u00fcr die 5. Klasse durch\u00adaus auch im LehrplanPLUS der Grund\u00ad\u00adschule suchen!) sowie Beispiele f\u00fcr Aufgaben. Dabei werden vor allem die im Vergleich zum Vorg\u00e4nger-Lehrplan neu hinzu gekommenen Aspekte ber\u00fccksichtigt, weniger das Altherge\u00adbrachte. Ikons, die zu Dokumen\u00adten f\u00fchren, sind farbig gestaltet; Ikons, hinter denen sich noch keine Dokumente befinden, sind grau.<\/p>\n<p><span style=\"color: #ff6600;\">Kommentare zu den Aufgaben des ISB finden Sie hier: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/M_B5_Aufgaben_LPplus_Kommentar.docx\">wor<span style=\"color: #ff6600;\">d<\/span><\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2019\/09\/M_B5_Aufgaben_LPplus_Kommentar.pdf\">pdf<\/a>]<br \/>\n<\/span><\/p>\n<p>In den Schwerpunkten Biologie und Naturwissenschaftliches Arbeiten (NA) l\u00e4sst der LehrplanPLUS trotz seiner detaillierten Forderungen erkennbare <strong>Freihei\u00adten<\/strong> in der Wahl der Feinlernziele, der Untersuchungen und Experimente, der Medien sowie der konkreten Umset\u00adzung des Kompetenz-Trainings (an\u00adders als z. B. in Phy\u00adsik).<\/p>\n<p><strong>Verbindlichkeit<\/strong>: W\u00e4hrend die im LehrplanPLUS aufgelisteten obligaten <strong>Fachinhalte<\/strong> vollst\u00e4n\u00addig im Unterricht zu behandeln sind (<strong>Minimal<\/strong>-Forderung), sind die Formulierungen im ersten Lernbereich (<strong>prozessbezogene Kompetenzen<\/strong>) als <strong>Maximal<\/strong>-Forderungen zu verstehen, deren vollst\u00e4ndige Erf\u00fcllung der Note 1* entspr\u00e4che. Das hei\u00dft, sie stellen Ziele dar, die stets angestrebt werden sollen, in der Regel aber nur bis zu einem gewissen Grad erreicht werden k\u00f6nnen.<\/p>\n<p>Nachhaltiges Lernen ist nur erreichbar durch kumulatives Lernen, d. h. durch mehrfache Anwendung des Gelernten in neuen Kontexten. Gerade eine enge Verschr\u00e4nkung von Biologie und Naturwissenschaftlichem Arbeiten in der 5. Klasse bietet eine beeindruckende F\u00fclle von M\u00f6glichkeiten daf\u00fcr.<span style=\"color: #ff6600;\"> Mehr dazu in diesem Skript: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/06\/DM_kumulatives_Lernen_5.Klasse.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/06\/DM_kumulatives_Lernen_5.Klasse.pdf\">pdf<\/a>]<\/span><\/p>\n<p>Das vorliegende Skript soll eventuell vorhandene Ber\u00fchrungs\u00e4ngste mit der Kompetenzorien\u00adtierung abmildern, indem es versucht, den Blick auf das Wesentliche zu lenken, in Anh\u00e4ngen aber auch kon\u00adkrete Beispiele zur Umsetzung des LehrplanPLUS anbietet.<\/p>\n<p><span style=\"color: #0000ff;\"><strong><span id=\"b5skript2a2\" class=\"sta-anchor \" aria-hidden=\"true\"><\/span>1\u00a0\u00a0\u00a0\u00a0 Erkenntnisse gewinnen<\/strong><\/span><\/p>\n<p>Die Sch\u00fcler sollen den Weg der naturwissenschaftlichen Erkenntnisgewinnung an m\u00f6glichst vielen verschiedenen Beispielen nachvollziehen. Dies basiert zum einen auf <strong>Experimenten<\/strong> (im engeren Sinn: mit Fragestellung, Versuchsanordnung, Beobachtung, Erkl\u00e4rung) und <strong>Untersuchungen<\/strong> (von den Sch\u00fclern bzw. von der Lehrkraft durchgef\u00fchrt bzw. durch Medien demonstriert) und zum anderen auf der Arbeit an <strong>Modellen<\/strong>.<\/p>\n<p>Die Sch\u00fcler \u201e<em>leiten aus dem Vergleich historischer und moderner Quellen ab, dass sich Wissen ver\u00ad\u00e4ndert und altes Wissen aufgrund neuer Erkenntnisse verworfen oder abge\u00e4ndert wird. \u2013 Entwicklung und Eigenschaften naturwissenschaftlichen Wissens: <strong>Ver\u00e4nderung von Wissen im Lauf der Zeit<\/strong>.&#8220;<\/em> Das l\u00e4sst sich beispielsweise bei der Bewegung des Blutes gut darstellen: W\u00e4hrend man lange von einer Hin- und Her-Bewegung ausgegangen ist, konnte William Harvey 1628 beweisen, dass das Blut im Kreislauf flie\u00dft (dass im 13. Jahrhundert der arabische Arzt Ibn an-Nafis bereits die selbe Erkenntnis hatte, war in Europa damals nicht bekannt). Packt man nicht noch mehr hinein, l\u00e4sst sich die Ver\u00e4nderung von Wissen im Lauf der Zeit an diesem Beispiel altersgem\u00e4\u00df und deshalb erfolgreich transportieren. <span style=\"color: #ff6600;\">Hier das Arbeitsblatt daf\u00fcr: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2019\/09\/AM_B5_Blutkreislauf_historisch_N4.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2019\/09\/AM_B5_Blutkreislauf_historisch_N4.pdf\">pdf<\/a>]<\/span><\/p>\n<p><span style=\"color: #0000ff;\"><strong><span id=\"b5skript2x11\" class=\"sta-anchor \" aria-hidden=\"true\"><\/span>1.1\u00a0\u00a0\u00a0\u00a0 Experimente und Untersuchungen<\/strong><\/span><\/p>\n<p>Unterst\u00fctzt durch die Erfahrungen aus den Untersuchungen im Schwerpunkt Naturwissen\u00adschaft\u00adliches Arbeiten verinnerlichen die Sch\u00fcler von Beispiel zu Beispiel immer st\u00e4rker die <strong>Phasen des naturwissenschaftlichen Erkenntniswegs<\/strong>:<\/p>\n<ul>\n<li>Fragestellungen erkennen<\/li>\n<li>Hypothesen (und Gegenhypothesen) formulieren<\/li>\n<li>naturwissenschaftliche Untersuchung planen und durchf\u00fchren<\/li>\n<li>Daten auswerten (d.\u00a0h. in sinnvoller Weise darstellen) und interpretieren.<\/li>\n<\/ul>\n<p>Zun\u00e4chst m\u00fcssen sie dabei sehr eng gef\u00fchrt werden, sollen mit der Zeit sie aber immer selb\u00adst\u00e4ndiger werden, indem sie die Fragestellungen bzw. Hypothesen mit immer weniger Einhilfen bzw. selbst finden oder indem sie \u201e<em>aus wenigen vorgegebenen Arbeitsweisen oder -techniken eine passende ausw\u00e4hlen&#8220;<\/em>. Im Idealfall entwerfen sie selbst einen sinnvollen Versuchsaufbau. Schlie\u00dflich f\u00fchren sie \u201e<em>nach Anlei\u00adtung ein\u00adfache naturwissenschaftliche Untersuchungen zu vorgegebenen Themen und Fragestellungen durch und verwenden dabei ggf. einfache Ger\u00e4te und Hilfsmittel&#8220;.<\/em> Sie verwenden dabei \u201e<em>naturwissen\u00adschaft\u00adliche <strong>Arbeitsweisen<\/strong>: u.\u00a0a. Beobachten, Vergleichen, Experimentieren&#8220; <\/em>sowie<em> \u201e<\/em><em>grundlegende <strong>Ar\u00adbeits\u00adtechniken<\/strong>: im Labor u.\u00a0a. Umgang mit Glasger\u00e4ten, Temperatur- und Massenbestimmung; im Frei\u00adland u.\u00a0a. Sammeln und Bestimmen von Pflanzen&#8220;<\/em> und erlernen \u201e<em>einfache Nachweisreaktionen: St\u00e4rke\u00adnachweis, Fettfleckprobe, Kalkwasserprobe, Glimmspanprobe&#8220;<\/em>. Wesentlich dabei ist das strikte \u201e<em>Beachten von <strong>Verhaltens- und Sicherheitsregeln<\/strong>&#8222;<\/em>, die halbj\u00e4hrlich besprochen werden m\u00fcssen (die Sch\u00fcler be\u00adst\u00e4\u00adtigen dies jeweils mit ihrer Unterschrift). Die Sch\u00fcler-Experimente und -Unter\u00adsuchungen finden in der Regel im Schwerpunkt Naturwissenschaftliches Arbeiten statt, auch dann, wenn der LehrplanPLUS die genannten Kompetenzen und ihre Inhalte im Lehrplan\u00adabschnitt f\u00fcr den Schwerpunkt Bio\u00adlogie auflistet.<\/p>\n<figure id=\"attachment_250\" aria-describedby=\"caption-attachment-250\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-250\" src=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Iodprobe-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Iodprobe-300x212.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Iodprobe-768x543.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Iodprobe-1024x724.jpg 1024w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Iodprobe.jpg 1984w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-250\" class=\"wp-caption-text\">Einf\u00fchrung des St\u00e4rkenachweises mit Kontrollversuchen: v. l. n. r. Wasser, Kochsalz-, Zucker- und St\u00e4rkel\u00f6sung, jeweils mit drei Tropfen Iod-L\u00f6sung (rechts) versetzt<\/figcaption><\/figure>\n<p>Im Idealfall wird aufgrund einer Beobachtung eine <strong>Fragestellung<\/strong> und daraus eine <strong>Hypothese<\/strong> (am besten mit Gegen-Hypothese) entwickelt, die anhand einer Untersuchung oder eines Modells \u00fcberpr\u00fcft und damit verifiziert oder falsifiziert wird. In der Regel sollten dabei \u00a0Kontrollversuche durchgef\u00fchrt werden (z.\u00a0B. wird die Iod-Probe au\u00dfer mit St\u00e4rke-L\u00f6sung auch mit Wasser, Kochsalz- und Zucker-L\u00f6sung durchgef\u00fchrt) bzw. Blindproben (Parallelversuche ohne die wirksame Substanz). Es ist sinnvoll, bereits in der 5. Klasse den Fachbegriff Hypothese einzuf\u00fchren: \u201eEine Hypothese ist eine Erkl\u00e4rungs-Idee, die richtig oder falsch sein kann.\u201c (Der Begriff \u201eThese\u201c ist zwar grunds\u00e4tzlich auch korrekt, ist aber viel allgemeiner gehalten wie z.\u00a0B. Luthers ber\u00fchmte Thesen.) Dabei sollte man auch betonen, dass das Erstellen einer Hypothese immer eine beachtliche Leistung darstellt, auch wenn sich durch das Experiment herausstellt, dass sie falsch ist &#8211; eine Erkenntnis, die auch \u00e4lteren Sch\u00fclern nicht ohne weiteres einleuchtet.<\/p>\n<p><span style=\"color: #ff6600;\"><em>Anregungen zur Kompetenzschulung durch Experimente enth\u00e4lt der Abschnitt zu Naturwissenschaftlichem Arbeit<span style=\"color: #ff6600;\">en (5. Klasse Skript 4). <\/span><\/em><\/span><\/p>\n<p><span style=\"color: #ff6600;\">Untersuchungen durchf\u00fchren in der 5. Klasse: Beispiele [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/12\/DM_NT5_Untersuchungen_durchfuehren.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/12\/DM_NT5_Untersuchungen_durchfuehren.pdf\">pdf<\/a>]<\/span><\/p>\n<p><span style=\"color: #ff6600;\">Hinweise zum Anlegen eines naturwissenschaftlichen Protokolls [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/04\/NA_Protokolle.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/04\/NA_Protokolle.pdf\"><span style=\"color: #ff6600;\">pd<\/span>f<\/a>]<\/span><\/p>\n<p>Die Sch\u00fcler \u201e<em>identifizieren bei einfachen naturwissenschaftlichen Untersuchungen m\u00f6gliche Fehlerquel\u00adlen und leiten daraus die Notwendigkeit gewissenhafter Planung sowie sorgf\u00e4ltigen Arbeitens zur Feh\u00adler\u00advermeidung ab&#8220;. <\/em>Dies l\u00e4sst sich beispielsweise beim Erhitzen von Wasser mit einer Kerzen\u00adflamme gut behandeln: Der Abstand zwischen Flammenspitze und Reagenzglasboden muss konstant sein (deshalb Stativ verwenden), die Flamme sollte immer gleich gro\u00df sein, das Wasser muss vor jeder Messung gleichm\u00e4\u00dfig durchger\u00fchrt werden, das Thermometer darf nicht auf dem erhitzten Reagenzglasboden aufsitzen, der Zeitpunkt der Messungen muss genau eingehalten werden, die Temperatur muss auf der Skala korrekt abgelesen werden usw.<\/p>\n<p>Im ersten Lernbereich des Schwerpunkts Biologie f\u00fchrt der LehrplanPLUS zwei konkrete biologische Unter\u00adsuchungen auf (die also obligat durchzuf\u00fchren sind):<\/p>\n<p style=\"padding-left: 30px;\"><strong>Untersuchung: Mikroskopieren<\/strong><\/p>\n<p>Die Sch\u00fcler lernen Aufbau und Bedienung des Lichtmikroskops kennen. Sie verwenden es \u201e<em>nach Anleitung, um tierische und pflanzliche Zellen zu betrachten, und erstellen nach konkreten Vor\u00adgaben beschriftete Zeichnungen der betrachteten einfachen biologischen Grundstrukturen&#8220;<\/em>. Sie stellen unter \u201e<em>Verwendung von Objekttr\u00e4ger und Deckgl\u00e4schen<\/em> <em>einfache Pr\u00e4parate ohne Schnitte her und f\u00e4r\u00adben diese ggf. an, um Bestandteile der Zellen besser erkennbar zu machen&#8220;<\/em> (das Anf\u00e4rben verlangt der LehrplanPLUS also nicht obligat).<\/p>\n<p><span style=\"color: #ff6600;\">Skript Mikroskopie Praktikum [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/06\/Mikroskopie-Praktikum.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/06\/Mikroskopie-Praktikum.pdf\"><span style=\"color: #ff6600;\">p<\/span>df<\/a>]<\/span><\/p>\n<p style=\"padding-left: 30px;\"><strong>Untersuchung: Einheimische Samenpflanzen<\/strong><\/p>\n<p>Die Sch\u00fcler \u201e<em>sammeln einheimische Samenpflanzen und bestimmen diese mithilfe einfacher Bestim\u00admungs\u00adliteratur (z.\u00a0B. bebilderter Bestimmungsb\u00fccher), um ihre Artenkenntnis zu erweitern&#8220;<\/em>. Beispielsweise entdecken die Sch\u00fcler im Freiland verschiedene bl\u00fchende Wiesenpflanzen, fotogra\u00adfie\u00adren Bl\u00fcte, Blatt oder Frucht und geben die Bilder in eine Pflanzenbestimmungs-App ein (z. B. \u201eGarden Blumen Identifizieren\u201c von zhang dan, kostenlos f\u00fcr iOS-Ger\u00e4te). Die App zeigt anhand eines Fotos mehrere Pflanzenarten an, die in Frage kommen, und die Sch\u00fcler forschen mit Internet-Seiten oder einem klassischen Bestimmungsbuch (z. B. Aichele: Was bl\u00fcht denn da?) weiter nach, bis sie ihre Pflanze m\u00f6glichst genau bestimmt haben. Die Verwendung elektronischer Medien wirkt einerseits, andererseits dient ihr zielorientierter Einsatz gleich\u00adzeitig der Medienerziehung.<\/p>\n<p><span style=\"color: #0000ff;\"><strong><span id=\"b5skript2x12\" class=\"sta-anchor \" aria-hidden=\"true\"><\/span>1.2\u00a0\u00a0\u00a0\u00a0 Modelle<\/strong><\/span><\/p>\n<p>Die Arbeit an und mit gegenst\u00e4ndlichen und Denk-Modellen soll im Vergleich zu fr\u00fcheren Zeiten k\u00fcnftig deutlich intensiviert werden. Dabei muss auch das Ph\u00e4nomen Modell an sich thematisiert werden: Die Sch\u00fcler \u201e<em>beschreiben Kennzeichen und Eigenschaften von Modellen und erkl\u00e4ren, wozu Modelle in der Biologie verwendet werden&#8220;.<\/em> Dabei nennen sie \u201e<em>Kennzeichen und Eigenschaften von materiellen Model\u00adlen: Unterschiede zum Original, z.\u00a0B. Hervorheben wesentlicher und Weglassen nebens\u00e4chlicher Eigen\u00adschaf\u00adten, anderes Material&#8220;, <\/em>und sie erkennen ihre \u201e<em>Verwendung zur Veranschaulichung&#8220;.<\/em><\/p>\n<figure id=\"attachment_249\" aria-describedby=\"caption-attachment-249\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-249\" src=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_2-300x116.jpg\" alt=\"\" width=\"300\" height=\"116\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_2-300x116.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_2-768x296.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_2-1024x395.jpg 1024w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_2.jpg 1075w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-249\" class=\"wp-caption-text\">Sehr naturnahes Holzmodell (dem man die Hilfe von Erwachsenen ansieht) mit Luftballons als Muskeln, wobei aber die Streckerfunktion nicht dargestellt wird.<\/figcaption><\/figure>\n<figure id=\"attachment_248\" aria-describedby=\"caption-attachment-248\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-248\" src=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_1-300x89.jpg\" alt=\"\" width=\"300\" height=\"89\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_1-300x89.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_1-768x228.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_1-1024x304.jpg 1024w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_NA_Armmodell_1.jpg 1030w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-248\" class=\"wp-caption-text\">Einfacheres Holzmodell mit korrekt montierten Luftballons als Muskeln, bei dem ein M\u00f6belscharnier und die Dicke der Holzleisten den korrekten Bewegungsablauf garantiert.<\/figcaption><\/figure>\n<p>Obligat ist die Verwendung von Modellen in der Menschenkunde: \u00a0Die Sch\u00fcler \u201e<em>informieren sich mithilfe von Struktur- und Funktionsmodellen \u00fcber anatomische Merkmale des menschlichen K\u00f6r\u00adpers&#8220;.<\/em> Auch erstellen sie<em> \u201e<\/em><em>nach Anleitung ein Modell zu einem biologischen Sachverhalt und verglei\u00adchen die Eigenschaften des Modells mit den tats\u00e4chlichen Verh\u00e4ltnissen in der Natur&#8220;<\/em>. Beispielsweise basteln sie (als NA-Hausaufgabe) ein Funktionsmodell zu Beuger- und Strecker-Muskel am Arm und pr\u00e4sen\u00adtieren es modellkritisch vor der Klasse.<\/p>\n<p><span style=\"color: #ff6600;\">Eine Anleitung dazu in Form einer Folie finden Sie hier: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/08\/AM_NA5_Armmodell.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/08\/AM_NA5_Armmodell.pdf\">pdf<\/a>])<\/span><\/p>\n<p><strong>Modellkritik<\/strong>, also der kritische Vergleich von Modell und Wirklichkeit, soll immer wieder mit den Sch\u00fcler ge\u00fcbt werden. Naturwissenschaften k\u00f6nnen die Natur nicht objektiv erfassen, sondern sie konstruieren jeweils Modelle, die st\u00e4ndig \u00fcber\u00adpr\u00fcft und verfeinert bzw. je nach Bedarf auch vergr\u00f6bert werden. F\u00fcr Sch\u00fcler ist es erfah\u00adrungs\u00adgem\u00e4\u00df sehr schwer zu akzeptieren, dass die Naturwissenschaften \u201enur\u201c Modelle anbie\u00adten k\u00f6nnen, nicht aber objektive Wahrheiten. Ebenso muss den Sch\u00fclern klar werden, dass die Qualit\u00e4t eines Modells nicht davon abh\u00e4ngt, wie viele Aspekte der Wirklichkeit es zeigt oder wie genau sie darstellt werden, sondern wie gut es f\u00fcr die Beantwortung einer Fragestellung geeignet ist (Weglassen bestimmter Aspekte lenkt weniger ab, Beschr\u00e4nkung auf wenige Aspekte schlie\u00dft beim Erproben Einfl\u00fcsse dieser weggelassenen Aspekte aus usw.).<\/p>\n<p><span style=\"color: #0000ff;\"><strong><span id=\"b5skript2a3\" class=\"sta-anchor \" aria-hidden=\"true\"><\/span>2\u00a0\u00a0\u00a0\u00a0 Kommunizieren<\/strong><\/span><\/p>\n<p><span style=\"color: #ff6600;\">Hier finden Sie das Skript zu Sprachsensiblem Unterricht (keine Angst: tut nicht weh!) [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/11\/DM_Sprache_im_BU.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/11\/DM_Sprache_im_BU.pdf\">pdf<\/a>]<\/span><\/p>\n<p>Kommunizieren im Sinne des LehrplanPLUS bedeutet neben Sprechen und Schreiben auch die Umwandlung von einer Kommunikationsform in eine andere, denn Fachsprache umfasst neben der Textform auch andere Darstellungsformen wie Tabellen, Diagramme oder Symbole (z.\u00a0B. chemische Formeln oder Wortgleichungen chemischer Reaktionen).<\/p>\n<p>Die Sch\u00fcler entnehmen unterschiedlichen Quellen Informationen und stellen sie in anderer Form dar. Als Quellen dienen Beobachtungen aus Untersuchungen und Experimenten, Filme und Animationen, Bilder, Skizzen, Schema-Zeichnungen, (nicht zu komplizierte) Diagramme, einfache Tabellen oder (wenn sie kindgerecht und sprachsensibel formuliert sind) Texte. In den Schulb\u00fcchern sind die Abbildungen meist gut f\u00fcr die Altersstufe geeignet, die Texte aber bez\u00fcglich Sprachniveau, Umfang und \u00dcbersichtlichkeit allzu oft nicht altersgem\u00e4\u00df.<\/p>\n<p>Anhand der Quellen fertigen die Sch\u00fcler einfache Texte, Tabellen, Diagramme oder \u00dcbersichtszeichnungen selbst an. Dabei soll immer wieder die Darstellungsform wech\u00adseln: Der Inhalt einer Tabelle wird in ein Diagramm \u00fcbertragen bzw. in Textform dargestellt; der Inhalt eines Diagramms sowie sein Kurvenverlauf werden verbalisiert; experimentell oder durch Erhebung gewonnene Daten werden in Tabellen dokumentiert und danach in einfachen Diagrammen dargestellt usw.<\/p>\n<figure id=\"attachment_262\" aria-describedby=\"caption-attachment-262\" style=\"width: 475px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-262\" src=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_Tabelle-300x36.jpg\" alt=\"\" width=\"475\" height=\"57\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_Tabelle-300x36.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_Tabelle-768x93.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_Tabelle.jpg 987w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><figcaption id=\"caption-attachment-262\" class=\"wp-caption-text\">Anhand eines Experiments (Erhitzen von Schnee \u00fcber einer Kerzenflamme) gewinnen die Sch\u00fcler Daten, die sie in einer Tabelle dokumentieren.<\/figcaption><\/figure>\n<figure id=\"attachment_261\" aria-describedby=\"caption-attachment-261\" style=\"width: 458px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-261\" src=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_S\u00e4ulendiagramm-300x195.jpg\" alt=\"\" width=\"458\" height=\"298\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_S\u00e4ulendiagramm-300x195.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_S\u00e4ulendiagramm-768x500.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_S\u00e4ulendiagramm.jpg 826w\" sizes=\"auto, (max-width: 458px) 100vw, 458px\" \/><figcaption id=\"caption-attachment-261\" class=\"wp-caption-text\">Die Sch\u00fcler erstellen anhand der Daten in der Tabelle ein S\u00e4ulendiagramm, das sie aus der Grundschule kennen. An der vertrauten Form \u00fcben sie das Anlegen der Achsen und das korrekte Eintragen der Werte. Neu ist, dass es deutlich mehr als nur drei S\u00e4ulen sind.<\/figcaption><\/figure>\n<figure id=\"attachment_260\" aria-describedby=\"caption-attachment-260\" style=\"width: 491px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-260\" src=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_Liniendiagramm-300x188.jpg\" alt=\"\" width=\"491\" height=\"308\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_Liniendiagramm-300x188.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_Liniendiagramm-768x481.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Wasser_Liniendiagramm.jpg 830w\" sizes=\"auto, (max-width: 491px) 100vw, 491px\" \/><figcaption id=\"caption-attachment-260\" class=\"wp-caption-text\">Erst wenn sie einige \u00dcbung mit der Anlage von S\u00e4ulendiagrammen haben, wird die neue Form des Liniendiagramms eingef\u00fchrt, am besten anhand eines bereits bekannten Beispiels.<\/figcaption><\/figure>\n<p>Ausgehend von einfachen <strong>S\u00e4ulendiagrammen<\/strong> (in der Grundschule mit bis zu 3 Werten) wer\u00adden mit den Sch\u00fclern umfangreichere S\u00e4ulendiagramme (vertikale, schmale Rechtecke), ggf. Balkendia\u00adgramme (horizontale, schmale Rechtecke) sowie <strong>Linien- oder Kurvendiagramme<\/strong> (allerdings nur bei Werten, die sich kon\u00adtinuierlich ver\u00e4ndern, nicht bei diskontinuierlichen Werten) entwickelt. Dabei ist sehr behutsam in kleinen Schritten vorzugehen. Alle wichtigen Gedanken sollten schriftlich fixiert und das Anlegen bzw. Verbalisieren von Diagrammen m\u00f6glichst oft einge\u00fcbt werden. (Ein Einstieg \u00fcber ein Liniendiagramm mit zwei Linien, wie in einem Schulbuch dargestellt, w\u00e4re absolut kontraproduktiv!) Von Anfang an sind die Sch\u00fcler dazu anzuhalten, Karopapier und Lineal zu verwenden sowie sehr sorgf\u00e4ltig zu zeichnen. (Ggf. Zusammenarbeit mit Geographie, wo in der 5. Klasse ebenfalls intensiv mit Diagrammen gearbeitet wird.)<\/p>\n<p><span style=\"color: #ff6600;\">Diagramm-Kompetenz Biologie 5. Klasse, Skript [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/12\/DM_NA5-Diagramm-Kompetenz-N4.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2018\/12\/DM_NA5-Diagramm-Kompetenz-N4.pdf\">pdf<\/a>]<\/span><\/p>\n<p><strong>Sprachsensibler Unterricht<\/strong>: Weil vielen Sch\u00fclern die f\u00fcr die Verbalisierung notwendigen Nomen und Adjektive, vor allem aber Verben und deren Pr\u00e4positionen fehlen, ist es sinnvoll, diese z. B. in Form von Wortlisten oder Wortfeldern vorzugeben. Bei Wortlisten kann das Problem auftreten, dass die Sch\u00fcler die Quellen kaum noch beachten und stattdessen aus den vorgegebenen W\u00f6rtern S\u00e4tze bilden, geleitet von deren Reihenfolge in der Liste. Dies wird vermieden, wenn die W\u00f6rter durcheinander stehen (und gegeneinander verdreht sind), so dass sich keine Reihenfolge ergibt. Abgestufte Einhilfen (von schwach nach stark) nach Josef Leisen:<\/p>\n<ul>\n<li>Ben\u00f6tigte wie \u00fcberfl\u00fcssige W\u00f6rter stehen als Wortfeld au\u00dferhalb der Quelle.<\/li>\n<li>Ausschlie\u00dflich ben\u00f6tigte W\u00f6rter stehen als Wortfeld au\u00dferhalb der Quelle.<\/li>\n<li>Ausschlie\u00dflich ben\u00f6tigte W\u00f6rter stehen als Wortliste au\u00dferhalb der Quelle.<\/li>\n<li>Jedes Wort steht direkt bei dem Element der Quelle, f\u00fcr das es ben\u00f6tigt wird.<\/li>\n<\/ul>\n<p>Die Sch\u00fcler verwenden bei der \u201e<em>Beschreibung von biologischen Sachverhalten und der Argumentation zu biologischen Themen Elemente der Fachsprache.<\/em> <em>Sie beantworten einfache biologische Fragestel\u00adlun\u00adgen, indem sie vorgegebene, auf einfachen Texten mit wenigen einfachen Darstellungsformen beruhende Quellen (Schulbuch, popul\u00e4rwissenschaftliche Quelle) auswerten&#8220;.<\/em><\/p>\n<p>Eine gute <strong>Fachsprache<\/strong> setzt eine angemessene Beherrschung der deutschen Sprache voraus. Zwar ist und bleibt die Erweiterung des alltagssprachlichen Wortschatzes oder die Behandlung der Grammatik Thema des Deutsch-Unterrichts, eine korrekte Fachsprache (Bildungssprache) kann aber nur im Fachunterricht vermittelt werden. Im Biologie-Unterricht werden neben naturwissen\u00adschaft\u00adlichen Fachbegriffen auch allgemein-sprachliche Begriffe eingef\u00fchrt, wenn sie im biologischen Kontext wichtig sind. Es ist sinnvoll (auch f\u00fcr deutsche Muttersprachler), bei Nomen stets das grammatikalische Geschlecht und die Pluralform anzugeben (und dann auch zu verlangen!) und bei unregelm\u00e4\u00dfigen Verben die Form des Imperfekt und das Partizip Perfekt.<\/p>\n<p>Auch in gro\u00dfen Klassen soll jeder Sch\u00fcler m\u00f6glichst viel Gelegenheit zu eigenem Formulieren erhalten; meist wird das in schriftlicher Form erfolgen. Daf\u00fcr ist entsprechend Zeit einzuplanen. Die wenigen von Zuhause sprachlich sehr gut gef\u00f6rderten Sch\u00fcler t\u00e4uschen oft dar\u00fcber hin\u00adweg, dass die meisten muttersprachlichen Zehnj\u00e4hrigen nur \u00fcber einen stark eingeschr\u00e4nkten Wortschatz, v. a. bei differenzierenden Verben und Adjektiven, verf\u00fcgen. Au\u00dferdem haben viele Sch\u00fcler mit Migrationshintergrund ganz allgemein Probleme mit Deutsch (wer in seiner Muttersprache gut alphabetisiert ist, hat keine Probleme, sich auch im Deutschen relativ schnell zurechtzufinden; die gro\u00dfen Problemf\u00e4lle sind Migrantenkinder, die in ihrer Muttersprache nicht gut alphabetisiert sind).<\/p>\n<p><em>Tipp von Josef Leisen: Verfassen Sie spontan ein Versuchsprotokoll in einer Fremdsprache. Sie werden feststellen, wie schwierig die Wortfindung ist und wie oft Begriffe dabei umschrieben werden m\u00fcssen.<\/em><\/p>\n<p>F\u00fcr sprachgehemmte Sch\u00fcler ist es sehr hilfreich, wenn sie zun\u00e4chst <strong>nonverbal<\/strong> einen Sachverhalt anhand von Modellen oder Tafelapplikationen darstellen k\u00f6nnen und bereits f\u00fcr diese Darstellung R\u00fcckmeldung von der Lehrkraft bekommen, bevor sie sich um die schwierige Verbalisierung des Sachverhalts bem\u00fchen.<\/p>\n<p>Exakte Darstellungsweise f\u00f6rdert das Verst\u00e4ndnis f\u00fcr den Weg der Erkenntnisgewinnung; deshalb m\u00fcssen von Experimenten und Untersuchungen sorgf\u00e4ltige <strong>Protokolle<\/strong> angefertigt werden. Der Lehrplan-PLUS nennt ver\u00adbindlich die \u201e<em>Bestandteile eines naturwissenschaftlichen Protokolls: Titel, Aufbau und Durchf\u00fchrung, Beobachtung, Auswertung und Interpretation&#8220;<\/em>. Dies entspricht der inhaltlich identi\u00adschen klassi\u00adschen Formulierung:<\/p>\n<ul>\n<li style=\"padding-left: 30px;\">F\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Fragestellung (Worum geht es?) bzw. Hypothese(n)<\/li>\n<li style=\"padding-left: 30px;\">VA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Versuchsaufbau (Was haben wir? Was tun wir?)<\/li>\n<li style=\"padding-left: 30px;\">B\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Beobachtung (Was sehen wir? \u2013 Scharf von der Erkl\u00e4rung trennen!)<\/li>\n<li style=\"padding-left: 30px;\">E\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Erkl\u00e4rung \/ Ergebnis (Was erkennen wir daraus?)<\/li>\n<\/ul>\n<p>Die Formulierung in Form einer Leitfrage (z. B. \u201eWas sehen wir?\u201c) unterst\u00fczt Sch\u00fcler, die mit dem Nominalstil (z.\u00a0B. \u201eBeobachtung\u201c) Schwierigkeiten haben.<\/p>\n<p><span style=\"color: #ff6600;\">Wichtige Hinweise zu sprachsensiblem Unterricht, der sprachliche \u00dcberforderung vermeidet, die Sch\u00fcler auf dem anstrengenden Weg des Erwerbs einer guten Fachsprache begleitet, finden Sie auf der Webseite von Josef Leisen: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.sprachsensiblerfachunterricht.de\">Link<\/a>]<\/span><\/p>\n<p><span style=\"color: #0000ff;\"><strong><span id=\"b5skript2a4\" class=\"sta-anchor \" aria-hidden=\"true\"><\/span>3\u00a0\u00a0\u00a0\u00a0 Bewerten<\/strong><\/span><\/p>\n<p>Gem\u00e4\u00df dem Entwicklungsstand der noch sehr jungen Sch\u00fcler bezieht sich der Kompe\u00adtenzbereich \u201eBewerten\u201c in der 5. Klasse ausschlie\u00dflich auf den <strong>eigenen K\u00f6rper<\/strong> (in der 6. Klas\u00adse dann auch auf auf andere Lebewesen). Die Sch\u00fcler \u201e<em>w\u00e4gen Folgen von Handlungen f\u00fcr die Gesunderhaltung des eigenen K\u00f6rpers ab, um bewusste Entscheidungen treffen zu k\u00f6nnen&#8220;<\/em>. Der Unter\u00adricht zielt dabei auf \u201e<em>Gesundheitsbewusstsein und Verantwortung: z.\u00a0B. Schutz der Sinnes\u00adorgane, ausgewogene Ern\u00e4hrung, sportliche Bet\u00e4tigung, Suchtgefahr&#8220;<\/em>. <span style=\"color: #ff6600;\">Vgl. das f\u00fcnfseitige Skript \u201eKompetenzbereich: Bewerten\u201c f\u00fcr die 5. und 6. Klasse im Serviceteil zum Lehr\u00adplanPLUS: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.lehrplanplus.bayern.de\/zusatzinformationen\/material\/lernbereich\/56364\/fachlehrplaene\/gymnasium\/5\/nt_gym\">pdf<\/a>]<\/span><\/p>\n<p>Im weiteren Sinne k\u00f6nnte man diesem Kompetenzbereich auch das <strong>Beurteilen<\/strong> zuordnen, beispielsweise die Beurteilung \u00fcber die Eignung eines Modells f\u00fcr eine bestimmte Fragestellung oder Hypothese bzw. beim Korrigieren von fehlerhaften Aussagen oder bildlichen Darstellungen. Im Gegensatz zu fr\u00fcheren Zeiten gilt die Korrektur von Fehlern durch Sch\u00fcler heute als effektive Lernmethode, solange unmissverst\u00e4ndlich klar gestellt ist, dass die vorgegebenen Darstellungen bewusst Fehler enthalten, welche zu korrigieren sind. Sch\u00fcler korrigieren gern und auffallend kritisch!<\/p>\n<figure id=\"attachment_267\" aria-describedby=\"caption-attachment-267\" style=\"width: 555px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-267\" src=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Fehlerbilder_Kreislauf-300x211.jpg\" alt=\"\" width=\"555\" height=\"390\" srcset=\"https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Fehlerbilder_Kreislauf-300x211.jpg 300w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Fehlerbilder_Kreislauf-768x540.jpg 768w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Fehlerbilder_Kreislauf-1024x720.jpg 1024w, https:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/IR_Fehlerbilder_Kreislauf.jpg 1354w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><figcaption id=\"caption-attachment-267\" class=\"wp-caption-text\">Nach der Behandlung des menschlichen Kreislaufs erhalten die Sch\u00fcler Skizzen dieser Art und beurteilen sie: Was ist gut dargestellt, was ist falsch dargestellt, was fehlt?<\/figcaption><\/figure>\n<p><span style=\"color: #ff6600;\">Hier finden Sie ein Beispiel f\u00fcr einen Fehlertext zum Thema Energieversorgung von Zellen f\u00fcr die Selbstevaluation der Sch\u00fcler: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/AM_B5_Fehlertext_Verdauung.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/07\/AM_B5_Fehlertext_Verdauung.pdf\">pdf<\/a>] sowie eine weitere Variante zum selben Thema: [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/08\/AM_B5_Fehlertext_Verdauung_2.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2017\/08\/AM_B5_Fehlertext_Verdauung_2.pdf\">pdf<\/a>]<\/span><\/p>\n<p><span style=\"color: #ff6600;\">Kompetenz-Training &#8222;Gewicht der Schultasche&#8220;, Larissa Arzt [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2019\/03\/AM_B6_Schultasche.docx\">word<\/a>] [<a style=\"color: #ff6600;\" href=\"http:\/\/www.bio-nickl.de\/wordpress\/wp-content\/uploads\/2019\/03\/AM_B6_Schultasche.pdf\">pdf<\/a>]<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Skript werden Hinweise zu den prozessbezogenen Kompetenzen gegeben, die schon immer Bestandteil eines guten Biologie-Unterrichts waren, jetzt aber genauer benannt und systematisiert werden und mit st\u00e4rkerer Gewichtung in den Unterricht eingebunden werden sollen. Dieses Skript wendet sich an Berufsanf\u00e4nger wie an erfahrene Lehrkr\u00e4fte, denn die Kompetenz-Orientierung ist in dieser Form und in diesem &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.bio-nickl.de\/wordpress\/did-meth-paed\/5-klasse-skript-2-kompetenz-training\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e5. Klasse Skript 2: Kompetenz-Training\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":150,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-172","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/pages\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":83,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/pages\/172\/revisions"}],"predecessor-version":[{"id":4214,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/pages\/172\/revisions\/4214"}],"up":[{"embeddable":true,"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/pages\/150"}],"wp:attachment":[{"href":"https:\/\/www.bio-nickl.de\/wordpress\/wp-json\/wp\/v2\/media?parent=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}